{"id":94,"count":3,"description":"<p style=\"text-align: center\" data-start=\"405\" data-end=\"562\"><strong data-start=\"410\" data-end=\"562\">Cases contempor\u00e0nies en venda a la Costa Brava definides per l\u00ednies netes, materials moderns, nobles... i una arquitectura orientada a l'espai i la confortabilitat.<\/strong><\/p>","link":"https:\/\/theonestate.com\/ca\/propiedades\/habitatges-contemporanis\/","name":"Habitatges contemporanis","slug":"habitatges-contemporanis","taxonomy":"propiedad_categoria","parent":82,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casas modernas en la Costa Brava | Viviendas exclusivas en venta<\/title>\n<meta name=\"description\" content=\"Casas modernas y contempor\u00e1neas en la Costa Brava. Viviendas exclusivas en venta con dise\u00f1o actual en las mejores localidades del Empord\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casas modernas en la Costa Brava | Viviendas exclusivas en venta\" \/>\n<meta property=\"og:description\" content=\"Casas modernas y contempor\u00e1neas en la Costa Brava. Viviendas exclusivas en venta con dise\u00f1o actual en las mejores localidades del Empord\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/\" \/>\n<meta property=\"og:site_name\" content=\"Theonestate\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theonestate.com\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-24-a-las-13.04.01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"358\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/theonestate.com\\\/propiedades\\\/casas-contemporaneas-en-costa-brava\\\/\",\"url\":\"https:\\\/\\\/theonestate.com\\\/propiedades\\\/casas-contemporaneas-en-costa-brava\\\/\",\"name\":\"Casas modernas en la Costa Brava | Viviendas exclusivas en venta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/theonestate.com\\\/#website\"},\"description\":\"Casas modernas y contempor\u00e1neas en la Costa Brava. Viviendas exclusivas en venta con dise\u00f1o actual en las mejores localidades del Empord\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/theonestate.com\\\/propiedades\\\/casas-contemporaneas-en-costa-brava\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/theonestate.com\\\/propiedades\\\/casas-contemporaneas-en-costa-brava\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/theonestate.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casas en venta\",\"item\":\"https:\\\/\\\/theonestate.com\\\/propiedades\\\/casas-venta-costa-brava\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casas contempor\u00e1neas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/theonestate.com\\\/#website\",\"url\":\"https:\\\/\\\/theonestate.com\\\/\",\"name\":\"The On Estate\",\"description\":\"Inmobiliaria de lujo en la Costa Brava (Girona, Espa\u00f1a). Venta, alquiler, gesti\u00f3n y rehabilitaci\u00f3n de propiedades exclusivas, incluyendo acceso a una colecci\u00f3n privada de propiedades off-market.\",\"publisher\":{\"@id\":\"https:\\\/\\\/theonestate.com\\\/#organization\"},\"alternateName\":\"The On Estate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/theonestate.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/theonestate.com\\\/#organization\",\"name\":\"The On Estate\",\"url\":\"https:\\\/\\\/theonestate.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/theonestate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/theonestate.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-logotipo_theonestate-1.png\",\"contentUrl\":\"https:\\\/\\\/theonestate.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-logotipo_theonestate-1.png\",\"width\":500,\"height\":500,\"caption\":\"The On Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/theonestate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/the_on_estate\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/the-on-estate\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casas modernas en la Costa Brava | Viviendas exclusivas en venta","description":"Casas modernas y contempor\u00e1neas en la Costa Brava. Viviendas exclusivas en venta con dise\u00f1o actual en las mejores localidades del Empord\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/","og_locale":"ca_ES","og_type":"article","og_title":"Casas modernas en la Costa Brava | Viviendas exclusivas en venta","og_description":"Casas modernas y contempor\u00e1neas en la Costa Brava. Viviendas exclusivas en venta con dise\u00f1o actual en las mejores localidades del Empord\u00e0.","og_url":"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/","og_site_name":"Theonestate","og_image":[{"width":358,"height":314,"url":"https:\/\/theonestate.com\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-24-a-las-13.04.01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/","url":"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/","name":"Casas modernas en la Costa Brava | Viviendas exclusivas en venta","isPartOf":{"@id":"https:\/\/theonestate.com\/#website"},"description":"Casas modernas y contempor\u00e1neas en la Costa Brava. Viviendas exclusivas en venta con dise\u00f1o actual en las mejores localidades del Empord\u00e0.","breadcrumb":{"@id":"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/theonestate.com\/propiedades\/casas-contemporaneas-en-costa-brava\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/theonestate.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Casas en venta","item":"https:\/\/theonestate.com\/propiedades\/casas-venta-costa-brava\/"},{"@type":"ListItem","position":3,"name":"Casas contempor\u00e1neas"}]},{"@type":"WebSite","@id":"https:\/\/theonestate.com\/#website","url":"https:\/\/theonestate.com\/","name":"The On Estate","description":"Inmobiliaria de lujo en la Costa Brava (Girona, Espa\u00f1a). Venta, alquiler, gesti\u00f3n y rehabilitaci\u00f3n de propiedades exclusivas, incluyendo acceso a una colecci\u00f3n privada de propiedades off-market.","publisher":{"@id":"https:\/\/theonestate.com\/#organization"},"alternateName":"The On Estate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theonestate.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/theonestate.com\/#organization","name":"The On Estate","url":"https:\/\/theonestate.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/theonestate.com\/#\/schema\/logo\/image\/","url":"https:\/\/theonestate.com\/wp-content\/uploads\/2026\/01\/cropped-logotipo_theonestate-1.png","contentUrl":"https:\/\/theonestate.com\/wp-content\/uploads\/2026\/01\/cropped-logotipo_theonestate-1.png","width":500,"height":500,"caption":"The On Estate"},"image":{"@id":"https:\/\/theonestate.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/the_on_estate\/","https:\/\/es.linkedin.com\/company\/the-on-estate"]}]}},"_links":{"self":[{"href":"https:\/\/theonestate.com\/ca\/wp-json\/wp\/v2\/propiedad_categoria\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theonestate.com\/ca\/wp-json\/wp\/v2\/propiedad_categoria"}],"about":[{"href":"https:\/\/theonestate.com\/ca\/wp-json\/wp\/v2\/taxonomies\/propiedad_categoria"}],"up":[{"embeddable":true,"href":"https:\/\/theonestate.com\/ca\/wp-json\/wp\/v2\/propiedad_categoria\/82"}],"wp:post_type":[{"href":"https:\/\/theonestate.com\/ca\/wp-json\/wp\/v2\/propiedad?propiedad_categoria=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}